{"id":145,"date":"2022-07-07T12:04:12","date_gmt":"2022-07-07T15:04:12","guid":{"rendered":"https:\/\/www.inovemidiaexterior.com.br\/blog\/?p=145"},"modified":"2022-07-07T12:04:13","modified_gmt":"2022-07-07T15:04:13","slug":"mesmo-com-o-avanco-digital-midia-exterior-e-parte-fundamental-da-estrategia-de-comunicacao","status":"publish","type":"post","link":"https:\/\/www.inovemidiaexterior.com.br\/blog\/mesmo-com-o-avanco-digital-midia-exterior-e-parte-fundamental-da-estrategia-de-comunicacao\/","title":{"rendered":"Mesmo com o avan\u00e7o digital, M\u00eddia Exterior \u00e9 parte fundamental da estrat\u00e9gia de comunica\u00e7\u00e3o"},"content":{"rendered":"\n<p>O digital \u00e9 essencial para uma estrat\u00e9gia de comunica\u00e7\u00e3o eficiente. Na cria\u00e7\u00e3o de um planejamento de m\u00eddia, \u00e9 imprescind\u00edvel pensar em todos os recursos que o ambiente online oferece para uma campanha de sucesso. Por\u00e9m, o grande erro dos clientes e profissionais de comunica\u00e7\u00e3o est\u00e1 em descartar a M\u00eddia Exterior dos planos de comunica\u00e7\u00e3o.<\/p>\n\n\n\n<p>Esse tipo de comportamento vai contra os h\u00e1bitos da sociedade atual. A Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas estima que, em 2050, mais da metade da popula\u00e7\u00e3o mundial habitar\u00e1 nos centros urbanos, o que significa uma import\u00e2ncia ainda maior das m\u00eddias OOH (ou out-of-home, fora de casa em tradu\u00e7\u00e3o livre do ingl\u00eas).<\/p>\n\n\n\n<p>De acordo com o estudo&nbsp;M\u00eddia Dados Brasil 2021, do Grupo de M\u00eddia S\u00e3o Paulo, a penetra\u00e7\u00e3o dos an\u00fancios publicit\u00e1rios atrav\u00e9s de OOH \u00e9 de 88% da popula\u00e7\u00e3o brasileira num total de 30 dias.&nbsp;<\/p>\n\n\n\n<p><strong>EXPOSI\u00c7\u00c3O DE MARCA O ANO INTEIRO:<\/strong><\/p>\n\n\n\n<p>Marcar presen\u00e7a na vida do consumidor somente em datas comemorativas n\u00e3o \u00e9 a melhor estrat\u00e9gia para uma comunica\u00e7\u00e3o eficiente. Estar presente em todos os formatos de m\u00eddia durante o ano inteiro \u00e9 essencial para marcar presen\u00e7a no cotidiano do seu p\u00fablico-alvo.<\/p>\n\n\n\n<p>\u00c9 para completar a jornada do consumidor que entra a M\u00eddia Exterior, uma vez que somente apostar em meios digitais n\u00e3o faz com que sua marca seja lembrada com totalidade.\u00a0Nessa modalidade de m\u00eddia temos: Outdoors, Pain\u00e9is, Front Lights, Empenas e Top Sights.<\/p>\n\n\n\n<p>Com a pandemia da Covid-19 e o isolamento social aumentou, ainda mais, a fun\u00e7\u00e3o social das m\u00eddias externas. Depois de quase dois anos, o fluxo nas ruas e avenidas aumentou e as pessoas passaram a dar mais import\u00e2ncia ao ato de sair de casa. Consequentemente, as marcas que cruzarem o caminho dessas pessoas estar\u00e3o ainda mais pr\u00f3ximas do cliente final nesse novo momento.&nbsp;A m\u00eddia de interven\u00e7\u00e3o, aliada \u00e0 pe\u00e7as criativas e que se destacam, \u00e9 sucesso na certa.<\/p>\n\n\n\n<p><strong>REFER\u00caNCIA:<\/strong><\/p>\n\n\n\n<p><em>G1. <\/em><strong>Mesmo com o avan\u00e7o digital, a M\u00eddia Exterior \u00e9 parte fundamental da estrat\u00e9gia de comunica\u00e7\u00e3o. <\/strong>Dispon\u00edvel em &lt;g1.globo.com\/sp\/bauru-marilia\/especial-publicitario\/grupo-sm3\/noticia\/2022\/05\/04\/mesmo-com-o-avanco-digital-midia-externa-e-parte-fundamental-da-estrategia-de-comunicacao.ghtml&gt;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O digital \u00e9 essencial para uma estrat\u00e9gia de comunica\u00e7\u00e3o eficiente. Na cria\u00e7\u00e3o de um planejamento de m\u00eddia, \u00e9 imprescind\u00edvel pensar em todos os recursos que o ambiente online oferece para uma campanha de sucesso. Por\u00e9m, o grande erro dos clientes e profissionais de comunica\u00e7\u00e3o est\u00e1 em descartar a M\u00eddia Exterior dos planos de comunica\u00e7\u00e3o. Esse [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":146,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[27,19],"_links":{"self":[{"href":"https:\/\/www.inovemidiaexterior.com.br\/blog\/wp-json\/wp\/v2\/posts\/145"}],"collection":[{"href":"https:\/\/www.inovemidiaexterior.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inovemidiaexterior.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inovemidiaexterior.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inovemidiaexterior.com.br\/blog\/wp-json\/wp\/v2\/comments?post=145"}],"version-history":[{"count":1,"href":"https:\/\/www.inovemidiaexterior.com.br\/blog\/wp-json\/wp\/v2\/posts\/145\/revisions"}],"predecessor-version":[{"id":147,"href":"https:\/\/www.inovemidiaexterior.com.br\/blog\/wp-json\/wp\/v2\/posts\/145\/revisions\/147"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovemidiaexterior.com.br\/blog\/wp-json\/wp\/v2\/media\/146"}],"wp:attachment":[{"href":"https:\/\/www.inovemidiaexterior.com.br\/blog\/wp-json\/wp\/v2\/media?parent=145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inovemidiaexterior.com.br\/blog\/wp-json\/wp\/v2\/categories?post=145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inovemidiaexterior.com.br\/blog\/wp-json\/wp\/v2\/tags?post=145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}